{"id":367,"count":41,"description":"Polvos finos Rilsan\nProducido a partir de un<strong>  fuente renovable<\/strong>  (aceite de ricino), los polvos finos Rilsan\u00ae son  <strong>duradero por naturaleza<\/strong>. Gracias a sus excelentes propiedades, se utilizan en una amplia gama de aplicaciones.\n\n<strong>Satisfacen algunos de los retos m\u00e1s exigentes en materia de materiales<\/strong> y combinan una excelente resistencia qu\u00edmica, facilidad de procesamiento, rendimiento a altas y bajas temperaturas, ligereza, flexibilidad, durabilidad, retorno de energ\u00eda y tenacidad general.","link":"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/","name":"Rilsan\u00ae Polvos Finos","slug":"polvos-finos-rilsan","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rilsan\u00ae Polvos Finos - Tetrachim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rilsan\u00ae Polvos Finos - Tetrachim\" \/>\n<meta property=\"og:description\" content=\"Polvos finos Rilsan Producido a partir de un fuente renovable (aceite de ricino), los polvos finos Rilsan\u00ae son duradero por naturaleza. Gracias a sus excelentes propiedades, se utilizan en una amplia gama de aplicaciones. Satisfacen algunos de los retos m\u00e1s exigentes en materia de materiales y combinan una excelente resistencia qu\u00edmica, facilidad de procesamiento, rendimiento a altas y bajas temperaturas, ligereza, flexibilidad, durabilidad, retorno de energ\u00eda y tenacidad general.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/\" \/>\n<meta property=\"og:site_name\" content=\"Tetrachim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Tetrachim\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/categoria-producto\\\/polvos-finos-rilsan\\\/\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/categoria-producto\\\/polvos-finos-rilsan\\\/\",\"name\":\"Rilsan\u00ae Polvos Finos - Tetrachim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/categoria-producto\\\/polvos-finos-rilsan\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/categoria-producto\\\/polvos-finos-rilsan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rilsan\u00ae Polvos Finos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/\",\"name\":\"Tetrachim\",\"description\":\"Rev\u00eatements high-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/#organization\",\"name\":\"Tetrachim\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-tetrachim.png\",\"contentUrl\":\"https:\\\/\\\/www.tetrachim.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-tetrachim.png\",\"width\":244,\"height\":51,\"caption\":\"Tetrachim\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Tetrachim\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tetrachim\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rilsan\u00ae Polvos Finos - Tetrachim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/","og_locale":"es_ES","og_type":"article","og_title":"Rilsan\u00ae Polvos Finos - Tetrachim","og_description":"Polvos finos Rilsan Producido a partir de un fuente renovable (aceite de ricino), los polvos finos Rilsan\u00ae son duradero por naturaleza. Gracias a sus excelentes propiedades, se utilizan en una amplia gama de aplicaciones. Satisfacen algunos de los retos m\u00e1s exigentes en materia de materiales y combinan una excelente resistencia qu\u00edmica, facilidad de procesamiento, rendimiento a altas y bajas temperaturas, ligereza, flexibilidad, durabilidad, retorno de energ\u00eda y tenacidad general.","og_url":"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/","og_site_name":"Tetrachim","twitter_card":"summary_large_image","twitter_site":"@Tetrachim","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/","url":"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/","name":"Rilsan\u00ae Polvos Finos - Tetrachim","isPartOf":{"@id":"https:\/\/www.tetrachim.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tetrachim.com\/es\/categoria-producto\/polvos-finos-rilsan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.tetrachim.com\/es\/"},{"@type":"ListItem","position":2,"name":"Rilsan\u00ae Polvos Finos"}]},{"@type":"WebSite","@id":"https:\/\/www.tetrachim.com\/es\/#website","url":"https:\/\/www.tetrachim.com\/es\/","name":"Tetrachim","description":"Rev\u00eatements high-tech","publisher":{"@id":"https:\/\/www.tetrachim.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tetrachim.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.tetrachim.com\/es\/#organization","name":"Tetrachim","url":"https:\/\/www.tetrachim.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tetrachim.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/07\/logo-tetrachim.png","contentUrl":"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/07\/logo-tetrachim.png","width":244,"height":51,"caption":"Tetrachim"},"image":{"@id":"https:\/\/www.tetrachim.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Tetrachim","https:\/\/www.linkedin.com\/company\/tetrachim\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.tetrachim.com\/es\/wp-json\/wp\/v2\/product_cat\/367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tetrachim.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.tetrachim.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.tetrachim.com\/es\/wp-json\/wp\/v2\/product?product_cat=367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}