{"id":100529,"date":"2020-11-13T22:15:07","date_gmt":"2020-11-13T21:15:07","guid":{"rendered":"https:\/\/www.tetrachim.com\/product\/856g-300-vernice-trasparente-fep-2\/"},"modified":"2026-09-02T11:21:30","modified_gmt":"2026-09-02T09:21:30","slug":"856g-300-finitura-fep-trasparente-2","status":"publish","type":"product","link":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/","title":{"rendered":"856G-300 Finitura FEP Trasparente"},"content":{"rendered":"<p>I rivestimenti antiaderenti FEP (copolimero di etilene propilene fluorato) si sciolgono e fluiscono durante la cottura per fornire pellicole non porose, una scelta naturale per le applicazioni di rilascio con bassa abrasione. Oltre al basso attrito, i rivestimenti FEP hanno eccellenti propriet\u00e0 antiaderenti e un&#8217;ottima resistenza chimica. La temperatura massima di utilizzo \u00e8 di 205\u00b0C in continuo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>856G-300 \u00e8 una finitura FEP a base d&#8217;acqua progettata per fornire eccellenti propriet\u00e0 antiaderenti e resistenza chimica e alla corrosione. I prodotti FEP liquidi sono una scelta naturale per le applicazioni di distacco a bassa abrasione. Sono utilizzati principalmente in applicazioni industriali di cottura e stampi. Gli strati pigmentati applicati come strato intermedio migliorano la resistenza alla permeazione del sistema di rivestimento.<\/p>\n<p>I primer consigliati sono 420G-71x e 470G-71x.<\/p>\n","protected":false},"featured_media":87451,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[614],"product_tag":[],"class_list":{"0":"post-100529","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"supplier-chemours-it","7":"market-carta-tessuto","8":"market-alimentare-panetteria-industriale","9":"market-imballaggio","10":"property-proprieta-antiadesive","11":"property-resistenza-chimica","12":"property-resistenza-alla-corrosione","13":"property-resistenza-alla-temperatura","14":"product_cat-teflon-rivestimenti-industriali","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>856G-300 Finitura FEP Trasparente - Tetrachim<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"856G-300 Finitura FEP Trasparente - Tetrachim\" \/>\n<meta property=\"og:description\" content=\"856G-300 \u00e8 una finitura FEP a base d&#039;acqua progettata per fornire eccellenti propriet\u00e0 antiaderenti e resistenza chimica e alla corrosione. I prodotti FEP liquidi sono una scelta naturale per le applicazioni di distacco a bassa abrasione. Sono utilizzati principalmente in applicazioni industriali di cottura e stampi. Gli strati pigmentati applicati come strato intermedio migliorano la resistenza alla permeazione del sistema di rivestimento.  I primer consigliati sono 420G-71x e 470G-71x.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tetrachim\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T09:21:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/09\/PackPaint20KG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Tetrachim\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/prodotto\\\/856g-300-finitura-fep-trasparente-2\\\/\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/prodotto\\\/856g-300-finitura-fep-trasparente-2\\\/\",\"name\":\"856G-300 Finitura FEP Trasparente - Tetrachim\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/prodotto\\\/856g-300-finitura-fep-trasparente-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/prodotto\\\/856g-300-finitura-fep-trasparente-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tetrachim.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/PackPaint20KG.jpg\",\"datePublished\":\"2020-11-13T21:15:07+00:00\",\"dateModified\":\"2026-09-02T09:21:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/prodotto\\\/856g-300-finitura-fep-trasparente-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/prodotto\\\/856g-300-finitura-fep-trasparente-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/prodotto\\\/856g-300-finitura-fep-trasparente-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/PackPaint20KG.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tetrachim.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/PackPaint20KG.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/prodotto\\\/856g-300-finitura-fep-trasparente-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"negozio\",\"item\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/negozio-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"856G-300 Finitura FEP Trasparente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/\",\"name\":\"Tetrachim\",\"description\":\"Rev\u00eatements high-tech\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/#organization\",\"name\":\"Tetrachim\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tetrachim.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-tetrachim.png\",\"contentUrl\":\"https:\\\/\\\/www.tetrachim.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-tetrachim.png\",\"width\":244,\"height\":51,\"caption\":\"Tetrachim\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tetrachim.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Tetrachim\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tetrachim\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"856G-300 Finitura FEP Trasparente - Tetrachim","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/","og_locale":"it_IT","og_type":"article","og_title":"856G-300 Finitura FEP Trasparente - Tetrachim","og_description":"856G-300 \u00e8 una finitura FEP a base d'acqua progettata per fornire eccellenti propriet\u00e0 antiaderenti e resistenza chimica e alla corrosione. I prodotti FEP liquidi sono una scelta naturale per le applicazioni di distacco a bassa abrasione. Sono utilizzati principalmente in applicazioni industriali di cottura e stampi. Gli strati pigmentati applicati come strato intermedio migliorano la resistenza alla permeazione del sistema di rivestimento.  I primer consigliati sono 420G-71x e 470G-71x.","og_url":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/","og_site_name":"Tetrachim","article_modified_time":"2026-09-02T09:21:30+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/09\/PackPaint20KG.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Tetrachim","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/","url":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/","name":"856G-300 Finitura FEP Trasparente - Tetrachim","isPartOf":{"@id":"https:\/\/www.tetrachim.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/#primaryimage"},"image":{"@id":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/09\/PackPaint20KG.jpg","datePublished":"2020-11-13T21:15:07+00:00","dateModified":"2026-09-02T09:21:30+00:00","breadcrumb":{"@id":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/#primaryimage","url":"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/09\/PackPaint20KG.jpg","contentUrl":"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/09\/PackPaint20KG.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.tetrachim.com\/it\/prodotto\/856g-300-finitura-fep-trasparente-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/www.tetrachim.com\/it\/"},{"@type":"ListItem","position":2,"name":"negozio","item":"https:\/\/www.tetrachim.com\/it\/negozio-2\/"},{"@type":"ListItem","position":3,"name":"856G-300 Finitura FEP Trasparente"}]},{"@type":"WebSite","@id":"https:\/\/www.tetrachim.com\/it\/#website","url":"https:\/\/www.tetrachim.com\/it\/","name":"Tetrachim","description":"Rev\u00eatements high-tech","publisher":{"@id":"https:\/\/www.tetrachim.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tetrachim.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tetrachim.com\/it\/#organization","name":"Tetrachim","url":"https:\/\/www.tetrachim.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tetrachim.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/07\/logo-tetrachim.png","contentUrl":"https:\/\/www.tetrachim.com\/wp-content\/uploads\/2020\/07\/logo-tetrachim.png","width":244,"height":51,"caption":"Tetrachim"},"image":{"@id":"https:\/\/www.tetrachim.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Tetrachim","https:\/\/www.linkedin.com\/company\/tetrachim\/"]}]}},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/www.tetrachim.com\/it\/wp-json\/wp\/v2\/product\/100529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tetrachim.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tetrachim.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tetrachim.com\/it\/wp-json\/wp\/v2\/media\/87451"}],"wp:attachment":[{"href":"https:\/\/www.tetrachim.com\/it\/wp-json\/wp\/v2\/media?parent=100529"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tetrachim.com\/it\/wp-json\/wp\/v2\/product_brand?post=100529"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tetrachim.com\/it\/wp-json\/wp\/v2\/product_cat?post=100529"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tetrachim.com\/it\/wp-json\/wp\/v2\/product_tag?post=100529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}